{"id":194,"date":"2025-09-01T07:23:00","date_gmt":"2025-09-01T05:23:00","guid":{"rendered":"https:\/\/maelrannou.fr\/baindemousse\/?p=194"},"modified":"2025-09-20T19:23:07","modified_gmt":"2025-09-20T17:23:07","slug":"dans-la-pow","status":"publish","type":"post","link":"https:\/\/maelrannou.fr\/baindemousse\/2025\/09\/01\/dans-la-pow\/","title":{"rendered":"Dans la pow \u00a0"},"content":{"rendered":"\n<p class=\"has-black-color has-text-color has-link-color has-small-font-size wp-elements-e13afa5201cd93aee7c2ea13b801e39b\"><strong>Compte-rendu d\u2019une rencontre avec Elo\u00efse Marseille, 27 janvier 2023 (FIBD)<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"606\" height=\"800\" src=\"https:\/\/maelrannou.fr\/baindemousse\/wp-content\/uploads\/sites\/4\/2025\/08\/Eloise-Marseille-2.jpg\" alt=\"\" class=\"wp-image-197\" srcset=\"https:\/\/maelrannou.fr\/baindemousse\/wp-content\/uploads\/sites\/4\/2025\/08\/Eloise-Marseille-2.jpg 606w, https:\/\/maelrannou.fr\/baindemousse\/wp-content\/uploads\/sites\/4\/2025\/08\/Eloise-Marseille-2-227x300.jpg 227w\" sizes=\"auto, (max-width: 606px) 100vw, 606px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-5f7b7b64fb54157c2b1aa1b27c6474f3\">Entre 12h et 13h le vendredi 27 janvier 2023, \u00e0 la suite de la tr\u00e8s po\u00e9tique et militante rencontre avec Julie Delporte, et toujours dans ce petit espace d\u00e9cloisonn\u00e9 du Nouveau Monde, les festivalier.\u00e8re.s d\u2019Angoul\u00eame ont eu l\u2019heureuse opportunit\u00e9 de rencontrer Elo\u00efse Marseille, jeune autrice qu\u00e9b\u00e9coise, illustratrice, peintre murale et tatoueuse.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4fdd538eb1115b91a63e187842780f4c\">La jeune artiste, aux m\u00e9dia multi-mati\u00e8res, venait + particuli\u00e8rement parler, dans le cadre de cette rencontre avec Sophie Gindensperger, de sa 1<sup>\u00e8re<\/sup> bande dessin\u00e9e, r\u00e9cemment parue, <em>Confessions d\u2019une femme normale<\/em> (Pow Pow, 2022). Tissant elle aussi le fil de l\u2019autobiographie, \u00e0 sa mani\u00e8re propre, pleine de clart\u00e9 et de jovialit\u00e9, l\u2019\u0153uvre raconte une relation au corps, cisaill\u00e9 entre les filets d\u2019une honte li\u00e9e \u00e0 la sexualit\u00e9, et ce que ce tabou cr\u00e9e de solitude en nous pla\u00e7ant dans un rapport conflictuel \u00e0 la normalit\u00e9.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-0126d33f85ca93d13aac4e9f071c1d12\">Sophie Gindensperger, qui animait la rencontre, a dans un premier temps propos\u00e9 \u00e0 l\u2019autrice de se concentrer sur les objectifs intimes de ses <em>Confessions<\/em>, qu\u2019elle a interpr\u00e9t\u00e9es comme une mise \u00e0 nu de son cheminement amoureux tr\u00e9buchant. Le conc\u00e9dant volontiers, Elo\u00efse Marseille a alors d\u00e9fini son \u0153uvre comme une exp\u00e9rience d\u2019\u00e9criture th\u00e9rapeutique et lib\u00e9ratrice, qui l\u2019aide, &#8211; ce qu\u2019elle esp\u00e8re aussi pour son lectorat -, \u00e0 se construire et se reconstruire affectivement. L\u2019artiste a en effet \u00e9voqu\u00e9 \u00e0 cette occasion les relectures qu\u2019elles avaient faites de ses journaux intimes \u00e9crits durant son adolescence et la compassion qu\u2019elle avait alors \u00e9prouv\u00e9e pour son moi pass\u00e9, \u00e9motion qui a nourri chez elle un d\u00e9sir de partager un v\u00e9cu qui a pu \u00eatre pesant, et quelquefois aussi, embarrassant, avec quelques exp\u00e9riences sexuelles cocasses.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-70542028f62033594b58d3270e9cf2e0\">Cette observation a amen\u00e9 l\u2019autrice \u00e0 r\u00e9fl\u00e9chir \u00e0 l\u2019inexistence de son \u00e9ducation sexuelle, qui a fait qu\u2019elle a d\u00e9couvert son sexe \u00e0 22 ans. Sans mots usuels pour exprimer, toute jeune fille, ces <em>papillons dans le poupou<\/em> qui s\u2019\u00e9veillaient soudainement en elle, &#8211; image que je trouve d\u2019un imaginaire merveilleux et que l\u2019autrice lit comme la preuve de l\u2019absence de cette \u00e9ducation -, Elo\u00efse Marseille a r\u00e9v\u00e9l\u00e9 qu\u2019elle avait alors tr\u00e8s t\u00f4t accord\u00e9 au dessin une fonction masturbatoire &#8211; fonction aussi pr\u00e9cis\u00e9ment, j\u2019ai alors pens\u00e9, de langage. L\u2019artiste a par ailleurs regrett\u00e9 qu\u2019en raison de cette absence de transmission des mots, ces apprentissages sexuels si essentiels soient finalement pris en charge par la pornographie <em>maintsream<\/em>, qui en d\u00e9place les r\u00e9alit\u00e9s plurielles et les enjeux. Expression dont les images g\u00e2chent beaucoup la relation d\u2019un individu \u00e0 sa propre sexualit\u00e9, cette instance \u00e9ducative improvis\u00e9e expose en effet une repr\u00e9sentation tr\u00e8s violente de la sexualit\u00e9, \u00e0 l\u2019inverse d\u2019une pornographie f\u00e9ministe, mais d\u2019une r\u00e9ception + confidentielle et le fait de petites bo\u00eetes de production avec une caisse de r\u00e9sonnance \u00e0 port\u00e9e limit\u00e9e. L\u2019autrice est alors revenue sur les injonctions qui avaient pes\u00e9 sur son regard de jeune femme et ce d\u00e9sir, tr\u00e8s fort, mais qui lui venait donc d\u2019ailleurs, d\u2019\u00eatre par exemple vue comme formant un couple avec son compagnon. Aussi ce regard d\u00e9centr\u00e9 a-t-il donc d\u00fb \u00eatre d\u00e9plac\u00e9 et d\u00e9l\u00e9gitim\u00e9 pour permettre l\u2019av\u00e8nement d\u2019un regard + libre et serein sur ces questions, et qui est un processus toujours en cours.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"992\" src=\"https:\/\/maelrannou.fr\/baindemousse\/wp-content\/uploads\/sites\/4\/2025\/08\/Eloise-Marseille-3.jpg\" alt=\"\" class=\"wp-image-198\" srcset=\"https:\/\/maelrannou.fr\/baindemousse\/wp-content\/uploads\/sites\/4\/2025\/08\/Eloise-Marseille-3.jpg 768w, https:\/\/maelrannou.fr\/baindemousse\/wp-content\/uploads\/sites\/4\/2025\/08\/Eloise-Marseille-3-232x300.jpg 232w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-4e2a0969aab5305caedecae7cb220007\">Ce regard nouveau, \u00e0 la fois tendre et qui proteste, a amen\u00e9 l\u2019animatrice \u00e0 aborder conjointement la question des \u00e9tapes de la cr\u00e9ation et celle de la r\u00e9ception de l\u2019\u0153uvre, devant ce geste de d\u00e9nuement lucide et souriant qui s\u2019y exprime. D\u2019abord, Elo\u00efse Marseille a pr\u00e9cis\u00e9 que le 1<sup>er<\/sup> ton recherch\u00e9 pendant l\u2019\u00e9criture avait \u00e9t\u00e9 celui de la l\u00e9g\u00e8ret\u00e9, mais que le livre avait finalement pris une autre tournure. Ce moment de la rencontre dit bien pour moi l\u2019\u00e9nergie intrins\u00e8que des textes, qui est telle qu\u2019ils \u00e9chappent quelquefois \u00e0 leurs auteurices en elleux-m\u00eames, comme pour vivre de leur vie autonome &#8211; t\u00e9moignage d\u00e9licat aussi \u00e0 mes yeux, dans le cas de l\u2019\u00e9criture autobiographique, d\u2019une progression toujours en cours du moi qui s\u2019\u00e9crit. Cette vibration de ce moi qui s\u2019\u00e9crit et qui change en s\u2019\u00e9crivant se lit aussi dans la construction de ces <em>Confessions<\/em>, que l\u2019autrice per\u00e7oit comme d\u00e9cousue, car elle n\u2019en avait de fait pas du tout pr\u00e9vu la densit\u00e9. Elo\u00efse Marseille s\u2019est par ailleurs \u00e9mue de la r\u00e9ception de son \u0153uvre par des hommes&nbsp;: plusieurs lui disent en effet se sentir beaucoup vus dans ses <em>Confessions<\/em>, ce qui m\u2019a laiss\u00e9e \u00e0 la fois curieuse et songeuse, surtout apr\u00e8s que l\u2019artiste a reconnu qu\u2019elle avait beaucoup de mal \u00e0 dessiner les gar\u00e7ons, sa th\u00e9orie \u00e9tant qu\u2019une intimit\u00e9 quotidienne avec le corps est n\u00e9cessaire pour savoir dessiner celui-ci. Ainsi donc d\u2019apr\u00e8s l\u2019artiste invit\u00e9e, on dessine mieux les filles quand on est une fille et les gar\u00e7ons quand on est un gar\u00e7on. Le regard le + \u00e9mouvant pour moi reste cependant celui de sa m\u00e8re&nbsp;: Elo\u00efse Marseille \u00e9tait persuad\u00e9e que celle-ci n\u2019allait pas aimer son livre mais apprendra \u00e0 la salle que sa m\u00e8re a en fait \u00e9t\u00e9 une lectrice enjou\u00e9e et compatissante et qui a, \u00e0 l\u2019occasion de la lecture des <em>Confessions<\/em> de sa fille, pris conscience de tout ce qu\u2019elle ne lui avait pas appris et qui retient de cette \u0153uvre qu\u2019elle aurait aim\u00e9 \u00eatre + pr\u00e9sente &#8211; t\u00e9moignage l\u00e0 aussi sensible \u00e0 mes yeux de ce que l\u2019\u00e9criture peut permettre de r\u00e9tablissement de liens que l\u2019on pensait, sinon rompus, du moins, et sans vraiment de bruit pour en appr\u00e9hender les cassures, \u00e9br\u00e9ch\u00e9s.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color has-link-color wp-elements-cb4fc3a7c0a80ed44d1fb7418be656b0\">En l\u2019occurrence, demandera en conclusion Sophie Gindensperger, de qui vient ce go\u00fbt de l\u2019exploration de la sexualit\u00e9 f\u00e9minine&nbsp;et comment l\u2019autrice invit\u00e9e tisse-t-elle des liens entre ses.ces univers artistiques ? Place-t-elle par exemple son \u0153uvre sous le patronage de la ma\u00eetresse de c\u00e9r\u00e9monie de cette 50<sup>e<\/sup> \u00e9dition du festival, Julie Doucet&nbsp;? Si elle partage cet entrain dans la d\u00e9couverte d\u2019une intimit\u00e9 f\u00e9minine et aussi dans la pluralit\u00e9 des approches artistiques, Elo\u00efse Marseille ne pense pas s\u2019inscrire dans le sillage de l\u2019autrice, dont elle ne d\u00e9couvre l\u2019\u0153uvre que depuis peu, et ne pense pas + largement s\u2019inscrire dans une lign\u00e9e, m\u00eame si elle reconna\u00eet que cette incapacit\u00e9 \u00e0 se situer vient sans doute du syndrome de l\u2019imposteur, particuli\u00e8rement d\u00e9velopp\u00e9 chez les autrices. Toutefois, elle reconna\u00eet apr\u00e8s r\u00e9flexion certains mod\u00e8les inspirants, telles que Cathon, \u00e9galement publi\u00e9e chez Pow Pow \u2013 d\u2019apr\u00e8s elle \u00e9diteur qui fait vraiment confiance \u00e0 ses autrices dans leur d\u00e9veloppement d\u2019une parole singuli\u00e8re -, et &nbsp;Mirion Malle, avec en particulier <em>C\u2019est comme \u00e7a que je disparais<\/em> (La ville br\u00fble, 2020), qui r\u00e9sonne avec une autre tr\u00e8s belle rencontre du festival, consacr\u00e9e \u00e0 l\u2019enveloppe corporelle dans la bande dessin\u00e9e f\u00e9minine. Elo\u00efse Marseille s\u2019est dit aussi pour terminer tr\u00e8s impressionn\u00e9e par les \u0153uvres de Brecht Evens, et + sp\u00e9cialement par son travail de manipulation de l\u2019espace, qui est pour elle un sujet familier, notamment, j\u2019ai pens\u00e9, en tant que peintre murale et tatoueuse, approches qui offrent n\u00e9cessairement des \u00e9tendues de cr\u00e9ation tr\u00e8s diff\u00e9rentes. Elo\u00efse Marseille apprendra d\u2019ailleurs \u00e0 la salle qu\u2019avec un trait particuli\u00e8rement graphique et aussi beaucoup d\u2019humour, elle s\u2019essaie \u00e0 inclure la bande dessin\u00e9e dans sa pratique du tatouage et ainsi \u00e0 assurer une continuit\u00e9 entre ces diff\u00e9rents espaces de cr\u00e9ation&nbsp;: une po\u00e9tique, finalement, d\u2019un peau \u00e0 peau, qui enseigne et permet une intimit\u00e9 \u00e9troite entre les arts, mais qui donne aussi par l\u00e0 m\u00eame un nouvel espace, et donc apprend, \u00e0 sa mani\u00e8re, la libert\u00e9.<\/p>\n\n\n\n<p class=\"has-small-font-size\">Toutes les images sont extraites de&nbsp;<em>Confessions d&rsquo;une femme normale<\/em>,&nbsp;Pow Pow, 2022<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compte-rendu d\u2019une rencontre avec Elo\u00efse Marseille, 27 janvier 2023 (FIBD) Entre 12h et 13h le vendredi 27 janvier 2023, \u00e0 la suite de la tr\u00e8s po\u00e9tique et militante rencontre avec Julie Delporte, et toujours dans ce petit espace d\u00e9cloisonn\u00e9 du Nouveau Monde, les festivalier.\u00e8re.s d\u2019Angoul\u00eame ont eu l\u2019heureuse opportunit\u00e9 de rencontrer Elo\u00efse Marseille, jeune autrice &hellip; <a href=\"https:\/\/maelrannou.fr\/baindemousse\/2025\/09\/01\/dans-la-pow\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Dans la pow \u00a0<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[31,22,68,15,66,64,65,67],"class_list":["post-194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-compte-rendus","tag-autobiographie","tag-bande-dessinee","tag-corps","tag-feminisme","tag-pow-pow","tag-quebec","tag-sexualite","tag-tatouage"],"_links":{"self":[{"href":"https:\/\/maelrannou.fr\/baindemousse\/wp-json\/wp\/v2\/posts\/194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maelrannou.fr\/baindemousse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maelrannou.fr\/baindemousse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maelrannou.fr\/baindemousse\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/maelrannou.fr\/baindemousse\/wp-json\/wp\/v2\/comments?post=194"}],"version-history":[{"count":5,"href":"https:\/\/maelrannou.fr\/baindemousse\/wp-json\/wp\/v2\/posts\/194\/revisions"}],"predecessor-version":[{"id":335,"href":"https:\/\/maelrannou.fr\/baindemousse\/wp-json\/wp\/v2\/posts\/194\/revisions\/335"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maelrannou.fr\/baindemousse\/wp-json\/wp\/v2\/media\/195"}],"wp:attachment":[{"href":"https:\/\/maelrannou.fr\/baindemousse\/wp-json\/wp\/v2\/media?parent=194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maelrannou.fr\/baindemousse\/wp-json\/wp\/v2\/categories?post=194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maelrannou.fr\/baindemousse\/wp-json\/wp\/v2\/tags?post=194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}