{"id":179,"date":"2018-08-01T17:10:03","date_gmt":"2018-08-01T15:10:03","guid":{"rendered":"http:\/\/maelrannou.fr\/vuedefrance\/?p=179"},"modified":"2018-08-01T18:11:19","modified_gmt":"2018-08-01T16:11:19","slug":"multiplication-partis","status":"publish","type":"post","link":"https:\/\/maelrannou.fr\/vuedefrance\/2018\/08\/01\/multiplication-partis\/","title":{"rendered":"La multiplication des partis"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-181\" src=\"https:\/\/maelrannou.fr\/vuedefrance\/wp-content\/uploads\/sites\/2\/2018\/08\/Sans-titre.jpg\" alt=\"\" width=\"982\" height=\"727\" srcset=\"https:\/\/maelrannou.fr\/vuedefrance\/wp-content\/uploads\/sites\/2\/2018\/08\/Sans-titre.jpg 982w, https:\/\/maelrannou.fr\/vuedefrance\/wp-content\/uploads\/sites\/2\/2018\/08\/Sans-titre-300x222.jpg 300w, https:\/\/maelrannou.fr\/vuedefrance\/wp-content\/uploads\/sites\/2\/2018\/08\/Sans-titre-768x569.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/div>\n<p align=\"JUSTIFY\">Lundi 30 juillet, <a href=\"https:\/\/ici.radio-canada.ca\/nouvelle\/1115556\/elections-2018-record-partis-politiques-autorises-45-ans\">un article de La Presse Canadienne largement repris<\/a> a expliqu\u00e9 que le Directeur g\u00e9n\u00e9ral des \u00e9lections du Qu\u00e9bec avait enregistr\u00e9 20 partis officiellement pour l&rsquo;\u00e9lection, et qu&rsquo;un 21\u00e8me pourrait m\u00eame \u00eatre habilit\u00e9 d&rsquo;ici la cl\u00f4ture le 15 septembre. En tous les cas c&rsquo;est d\u00e9j\u00e0 un record : \u00ab Jamais, dans l&rsquo;histoire r\u00e9cente du Qu\u00e9bec, on n&rsquo;a atteint la vingtaine de partis \u00bb \u00e9crit La Presse Canadienne. Et de rappeler qu&rsquo;en 2012 les 18 partis accr\u00e9dit\u00e9s battaient d\u00e9j\u00e0 l&rsquo;ancien maximum.<\/p>\n<p align=\"JUSTIFY\">Hasard de calendrier, cette annonce sort en m\u00eame temps qu&rsquo;<a href=\"https:\/\/partis.projetarcadie.com\/\">un site fran\u00e7ais lanc\u00e9 par Tris Acatrinei, du Projet Arcadie, visant \u00e0 recenser tous les partis politiques fran\u00e7ais<\/a> \u2013 actuels mais aussi pass\u00e9s \u2013 et leur date de cr\u00e9ation, adresse, dirigeant etc. Ce site vient de na\u00eetre, il offre une base de donn\u00e9e utile et prendra sans doute en ampleur au cours des ans. L\u00e0 o\u00f9 le rapport avec le Qu\u00e9bec est int\u00e9ressant est qu&rsquo;il recense&#8230; 541 partis en activit\u00e9s.<\/p>\n<p align=\"JUSTIFY\">Pourquoi une telle distorsion entre le Qu\u00e9bec et la France ? Il y a bien sur plusieurs biais :<\/p>\n<ul>\n<li>\n<p align=\"JUSTIFY\">La population, la France a plus de huit fois plus d&rsquo;habitants (est 8 fois plus importante), avoir plus de partis peut sembler logique ;<\/p>\n<\/li>\n<li>\n<p align=\"JUSTIFY\">En France des partis servent \u00e0 tous les \u00e9chelons (municipal, r\u00e9gional, national, europ\u00e9en, etc.) mais il existe aussi des partis strictement municipaux ou r\u00e9gionaux, alors qu&rsquo;au Canada chaque \u00e9chelon (f\u00e9d\u00e9ral, provincial, municipal) est distinct et \u00e0 ses partis. Il faudrait donc ne comparer les partis provinciaux qu&rsquo;au nombre de partis se \u00a0pr\u00e9sentant aux \u00e9lections l\u00e9gislatives, par exemple \u2013 ce qui n\u2019exclurait pas des partis locaux, comme les autonomistes Bretons o\u00f9 les ind\u00e9pendantistes Kanaks ;<\/p>\n<\/li>\n<li>\n<p align=\"JUSTIFY\">Le nombre d&rsquo;\u00e9chelons territorial est plus important en France qu&rsquo;au Canada, on y retrouve pas moins de 35300 communes, plus des d\u00e9partements, des r\u00e9gions, l\u2019\u00c9tat (en deux chambres) et le parlement europ\u00e9en.<\/p>\n<\/li>\n<\/ul>\n<p align=\"JUSTIFY\">Cependant, s&rsquo;il faudrait r\u00e9duire un peu le chiffre de 541 partis fran\u00e7ais pour avoir une comparaison parfaite, cette liste pr\u00e9sente bien les partis reconnus comme tels aupr\u00e8s des institutions comp\u00e9tentes, et ne prend pas en compte les multiples associations politiques, par exemple cr\u00e9\u00e9s pour porter une candidature aux municipales. Cette reconnaissance comme parti entend des d\u00e9marches particuli\u00e8res rigoureuses et permet des d\u00e9ductions fiscales plus importantes. Elle permet aussi d&rsquo;\u00eatre d\u00e9clar\u00e9 pour avoir droit au financement public.<\/p>\n<p align=\"JUSTIFY\">La cr\u00e9ation de ces multiples partis est une astuce souvent utilis\u00e9e pour permettre de fragmenter ses dons, par exemple si le parti d&rsquo;un \u00e9lu que l&rsquo;on aime bien ne nous pla\u00eet pas, ce dernier peut cr\u00e9er un parti pour recevoir des dons qu&rsquo;il pourra utiliser de mani\u00e8re plus performante. On l&rsquo;a vu lors de la pr\u00e9sidentielle o\u00f9 l&rsquo;argent ramass\u00e9 lors de la primaire de droite est all\u00e9 \u00e0 Force R\u00e9publicaine, le parti de Fran\u00e7ois Fillon, et pas au parti organisateur. S&rsquo;ils ont finalement trouv\u00e9 un accord financier le micro-parti permettait de \u00ab capter \u00bb des sommes et d&rsquo;avoir une s\u00e9curit\u00e9 financi\u00e8re en ne d\u00e9pendant pas d&rsquo;une structure moins personnelle.<\/p>\n<p align=\"JUSTIFY\">L\u2019inexistence de ces multiples structures au Qu\u00e9bec tient sans doute tant \u00e0 une histoire politique diff\u00e9rente \u2013 avec un poids historique du bipartisme anglo-saxon, m\u00eame s&rsquo;il est aujourd&rsquo;hui plut\u00f4t un tri voir quadripartisme dans la plupart des parlements du Canada \u2013 qu&rsquo;\u00e0 des r\u00e8gles aussi bien de constitution que d&rsquo;existence bien plus strictes.<\/p>\n<p align=\"JUSTIFY\">Pour ce qui est des dons, la France autorise 7500 \u20ac de dons par ans et par personne (avec une limite au double par foyer), auquel peuvent s&rsquo;ajouter 4600 \u20ac de dons \u00e0 un candidat ou pour une \u00e9lection pr\u00e9cise, le tout d\u00e9ductible \u00e0 66 % des imp\u00f4ts (jusqu&rsquo;\u00e0 20% du total). Si les dons sont v\u00e9rifi\u00e9s, les noms sont indisponibles au public. Au Qu\u00e9bec un \u00e9lecteur peut donner au maximum 100 $ par parti par an, somme qu&rsquo;il peut doubler en cas d&rsquo;\u00e9lection. Un site d\u00e9di\u00e9 permet de voir le nom de chaque donateur associ\u00e9 \u00e0 sa la ville, son code postal et au d\u00e9tail des sommes vers\u00e9es sur plusieurs ann\u00e9es. \u00a0Les partis ne peuvent a priori pas se financer entre eux, comme c&rsquo;est le cas en France, ce qui \u00e9vite des jeux de transit entre diff\u00e9rente caisses (la tradition de l&rsquo;accord politique avec plusieurs logos sur une affiche est aussi inexistante), on note enfin que les sommes sont bien plus modestes, suite \u00e0 un changement de loi en 2014, d&rsquo;autant que cette modification a aussi supprim\u00e9 le cr\u00e9dit d&rsquo;imp\u00f4t pour les dons.<\/p>\n<p align=\"JUSTIFY\">Au-del\u00e0 des dons, qui sont certes une ressource (et la seule de la grande majorit\u00e9 des 541 partis fran\u00e7ais puisque seuls 16 d&rsquo;entre eux ont acc\u00e8s au financement public), la mani\u00e8re de cr\u00e9er un parti diff\u00e8re aussi. En France, il suffit de cr\u00e9er une \u00a0association loi 1901 \u00e0 caract\u00e8re politique. Pour cela il suffit de deux personnes, d&rsquo;une adresse et de r\u00e9gler le co\u00fbt de la publication au Journal officiel, puis de cr\u00e9er une deuxi\u00e8me association loi 1901 d\u00e9di\u00e9e, elle, au financement du parti. Une fois cela fait, l&rsquo;agr\u00e9ment arrive simplement et il est tr\u00e8s facile de jouer sur les micro-partis pour amasser des sommes et les transvaser entre partis (une pratique que je ne crois pas autoris\u00e9e au Qu\u00e9bec, sauf en cas de fusion stricte).<\/p>\n<p align=\"JUSTIFY\">Au Qu\u00e9bec, les choses sont plus radicales : un parti peut au minimum avoir cent adh\u00e9rents, que le DGEQ va contacter un par un pour v\u00e9rifier leur volont\u00e9 d&rsquo;appartenance (quitte \u00e0 demander une liste compl\u00e9mentaire), d\u00e9poser 500 $ de caution (rembours\u00e9e apr\u00e8s le premier rapport financier valide) et pr\u00e9senter des candidats aux \u00e9lections. Apr\u00e8s plusieurs ann\u00e9es sans pr\u00e9senter de candidats aux \u00e9lections g\u00e9n\u00e9rales ou partielles, les partis sont radi\u00e9s d&rsquo;office. Ainsi, les partis ont une \u00ab obligation d&rsquo;existence \u00bb et ne peuvent bien longtemps rester des coquilles vides servant \u00e0 \u00e9pargner pour des jours meilleurs ou au possible lancement d&rsquo;une carri\u00e8re personnelle.<\/p>\n<p align=\"JUSTIFY\">Dans la plupart des articles, on note une analyse expliquant que des partis plus nombreux ne sont pas forc\u00e9ment le signe d&rsquo;une meilleure d\u00e9mocratie, les participations aux \u00e9lections baissant en parall\u00e8le. S&rsquo;il me semble un peu sp\u00e9cieux de faire une corr\u00e9lation directe entre ces \u00e9l\u00e9ments, il semble cependant que le syst\u00e8me qu\u00e9b\u00e9cois et ses 21 partis gagne le combat de la transparence et de la clart\u00e9 sur un syst\u00e8me fran\u00e7ais o\u00f9 tout semble fait pour pouvoir r\u00e9ussir \u00e0 bidouiller malgr\u00e9 des lois de r\u00e9gulations de plus en plus fermes (et c&rsquo;est heureux) depuis les ann\u00e9es quatre-vingt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lundi 30 juillet, un article de La Presse Canadienne largement repris a expliqu\u00e9 que le Directeur g\u00e9n\u00e9ral des \u00e9lections du Qu\u00e9bec avait enregistr\u00e9 20 partis officiellement pour l&rsquo;\u00e9lection, et qu&rsquo;un 21\u00e8me pourrait m\u00eame \u00eatre habilit\u00e9 d&rsquo;ici la cl\u00f4ture le 15 septembre. En tous les cas c&rsquo;est d\u00e9j\u00e0 un record : \u00ab Jamais, dans l&rsquo;histoire r\u00e9cente &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/maelrannou.fr\/vuedefrance\/2018\/08\/01\/multiplication-partis\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;La multiplication des partis&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[221,62,56,219,220,97,222,212,213,13],"class_list":["post-179","post","type-post","status-publish","format-standard","hentry","category-chronique","tag-dons","tag-elections","tag-france","tag-partis","tag-partis-politiques","tag-politique","tag-politique-provinciale","tag-polqc","tag-qcpol","tag-quebec"],"_links":{"self":[{"href":"https:\/\/maelrannou.fr\/vuedefrance\/wp-json\/wp\/v2\/posts\/179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maelrannou.fr\/vuedefrance\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maelrannou.fr\/vuedefrance\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maelrannou.fr\/vuedefrance\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/maelrannou.fr\/vuedefrance\/wp-json\/wp\/v2\/comments?post=179"}],"version-history":[{"count":6,"href":"https:\/\/maelrannou.fr\/vuedefrance\/wp-json\/wp\/v2\/posts\/179\/revisions"}],"predecessor-version":[{"id":186,"href":"https:\/\/maelrannou.fr\/vuedefrance\/wp-json\/wp\/v2\/posts\/179\/revisions\/186"}],"wp:attachment":[{"href":"https:\/\/maelrannou.fr\/vuedefrance\/wp-json\/wp\/v2\/media?parent=179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maelrannou.fr\/vuedefrance\/wp-json\/wp\/v2\/categories?post=179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maelrannou.fr\/vuedefrance\/wp-json\/wp\/v2\/tags?post=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}